{"id":3887,"date":"2019-05-28T08:50:41","date_gmt":"2019-05-28T08:50:41","guid":{"rendered":"https:\/\/duettorent.nl\/?page_id=3887"},"modified":"2020-05-18T15:31:50","modified_gmt":"2020-05-18T15:31:50","slug":"condizioni-generali","status":"publish","type":"page","link":"https:\/\/duettorent.nl\/it\/condizioni-generali\/","title":{"rendered":"Condizioni Generali"},"content":{"rendered":"<p>Condizioni Generali di Duetto Rent 1 Definizione dei termini In queste Condizioni Generali, si intendono con:1.1 &nbsp;VVeicolo: veicoli a motore, nel senso di automobile, camper, furgone da trasporto o motorino, essendo l\u2019oggetto del contratto di locazione. DUETTO RENT <a href=\"https:\/\/duettorent.nl\/it\/condizioni-generali\/\" title=\"Read more on Condizioni Generali\" class=\"more-link\">read more<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condizioni Generali di Duetto Rent 1 Definizione dei termini In queste Condizioni Generali, si intendono con:1.1 &nbsp;VVeicolo: veicoli a motore, nel senso di automobile, camper, furgone da trasporto o motorino, essendo l\u2019oggetto del contratto di locazione. DUETTO RENT read more<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":101,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3887","page","type-page","status-publish","hentry","no-thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Condizioni Generali | Duetto Rent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/duettorent.nl\/it\/condizioni-generali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condizioni Generali | Duetto Rent\" \/>\n<meta property=\"og:description\" content=\"Condizioni Generali di Duetto Rent 1 Definizione dei termini In queste Condizioni Generali, si intendono con:1.1 &nbsp;VVeicolo: veicoli a motore, nel senso di automobile, camper, furgone da trasporto o motorino, essendo l\u2019oggetto del contratto di locazione. DUETTO RENT read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/duettorent.nl\/it\/condizioni-generali\/\" \/>\n<meta property=\"og:site_name\" content=\"Duetto Rent\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-18T15:31:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/condizioni-generali\\\/\",\"url\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/condizioni-generali\\\/\",\"name\":\"Condizioni Generali | Duetto Rent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/#website\"},\"datePublished\":\"2019-05-28T08:50:41+00:00\",\"dateModified\":\"2020-05-18T15:31:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/condizioni-generali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/duettorent.nl\\\/it\\\/condizioni-generali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/condizioni-generali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condizioni Generali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/\",\"name\":\"Duetto Rent\",\"description\":\"Italiaanse klassieke autoverhuur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/duettorent.nl\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condizioni Generali | Duetto Rent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/duettorent.nl\/it\/condizioni-generali\/","og_locale":"it_IT","og_type":"article","og_title":"Condizioni Generali | Duetto Rent","og_description":"Condizioni Generali di Duetto Rent 1 Definizione dei termini In queste Condizioni Generali, si intendono con:1.1 &nbsp;VVeicolo: veicoli a motore, nel senso di automobile, camper, furgone da trasporto o motorino, essendo l\u2019oggetto del contratto di locazione. DUETTO RENT read more","og_url":"https:\/\/duettorent.nl\/it\/condizioni-generali\/","og_site_name":"Duetto Rent","article_modified_time":"2020-05-18T15:31:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"19 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/duettorent.nl\/it\/condizioni-generali\/","url":"https:\/\/duettorent.nl\/it\/condizioni-generali\/","name":"Condizioni Generali | Duetto Rent","isPartOf":{"@id":"https:\/\/duettorent.nl\/it\/#website"},"datePublished":"2019-05-28T08:50:41+00:00","dateModified":"2020-05-18T15:31:50+00:00","breadcrumb":{"@id":"https:\/\/duettorent.nl\/it\/condizioni-generali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/duettorent.nl\/it\/condizioni-generali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/duettorent.nl\/it\/condizioni-generali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/duettorent.nl\/it\/"},{"@type":"ListItem","position":2,"name":"Condizioni Generali"}]},{"@type":"WebSite","@id":"https:\/\/duettorent.nl\/it\/#website","url":"https:\/\/duettorent.nl\/it\/","name":"Duetto Rent","description":"Italiaanse klassieke autoverhuur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/duettorent.nl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/pages\/3887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/comments?post=3887"}],"version-history":[{"count":0,"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/pages\/3887\/revisions"}],"wp:attachment":[{"href":"https:\/\/duettorent.nl\/it\/wp-json\/wp\/v2\/media?parent=3887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}